{"id":407,"date":"2018-01-06T02:30:51","date_gmt":"2018-01-06T01:30:51","guid":{"rendered":"http:\/\/www.cvjm-ofterdingen.de\/cvjm_wp\/?post_type=tribe_events&amp;p=407"},"modified":"2018-01-06T02:30:51","modified_gmt":"2018-01-06T01:30:51","slug":"christbaumsammlung-2018","status":"publish","type":"tribe_events","link":"https:\/\/www.cvjm-ofterdingen.de\/wp01\/event\/christbaumsammlung-2018\/","title":{"rendered":"Christbaumsammlung 2018"},"content":{"rendered":"<p>Am Sa, den 13. Januar sammeln wir wieder Christb\u00e4ume in Ofterdingen ein. Dazu sollte dein Christbaum ab 10 Uhr an der Stra\u00dfe stehen.<\/p>\n<ul>\n<li>Pro Baum sammeln wir 3 Euro ein.<\/li>\n<li>Bitte befestige am Baum deinen Namen und deine Hausnummer, damit wir klingeln k\u00f6nnen, um das Geld abzuholen.<\/li>\n<li>Das Geld wird zur H\u00e4lfte f\u00fcr die Jugendarbeit unseres Vereins verwendet (Zeltlager, Kinderfr\u00fchst\u00fcck etc.), die andere H\u00e4lfte spenden wir an ___ (Infos folgen demn\u00e4chst).<\/li>\n<\/ul>\n<p>Vielen Dank, dass wir auch deinen Christbaum mitnehmen d\u00fcrfen!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Sa, den 13. Januar sammeln wir wieder Christb\u00e4ume in Ofterdingen ein. Dazu sollte dein Christbaum ab 10 Uhr an der Stra\u00dfe stehen. Pro Baum sammeln wir 3 Euro ein. Bitte befestige am Baum deinen Namen und deine Hausnummer, damit &hellip; <a href=\"https:\/\/www.cvjm-ofterdingen.de\/wp01\/event\/christbaumsammlung-2018\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":410,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[40,41,42,94,123,134],"tribe_events_cat":[176,178,182],"class_list":["post-407","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-christbaum","tag-christbaeume","tag-christbaumsammlung","tag-jugendarbeit","tag-sammlung","tag-spende","tribe_events_cat-christbaumsammlung","tribe_events_cat-erwachsene","tribe_events_cat-familien","cat_christbaumsammlung","cat_erwachsene","cat_familien"],"_links":{"self":[{"href":"https:\/\/www.cvjm-ofterdingen.de\/wp01\/wp-json\/wp\/v2\/tribe_events\/407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cvjm-ofterdingen.de\/wp01\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.cvjm-ofterdingen.de\/wp01\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.cvjm-ofterdingen.de\/wp01\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.cvjm-ofterdingen.de\/wp01\/wp-json\/wp\/v2\/tribe_events\/407\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cvjm-ofterdingen.de\/wp01\/wp-json\/wp\/v2\/media?parent=407"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cvjm-ofterdingen.de\/wp01\/wp-json\/wp\/v2\/tags?post=407"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.cvjm-ofterdingen.de\/wp01\/wp-json\/wp\/v2\/tribe_events_cat?post=407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}